{"id":1975,"date":"2021-04-30T09:26:09","date_gmt":"2021-04-30T09:26:09","guid":{"rendered":"https:\/\/dehispa.com\/?page_id=1975"},"modified":"2025-05-12T13:28:08","modified_gmt":"2025-05-12T13:28:08","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_cta title=\u00bbPOL\u00cdTICA DE PRIVACIDAD\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh1&#8243; header_font_size=\u00bb40px\u00bb body_font_size=\u00bb18px\u00bb background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/dehispa.com\/wp-content\/uploads\/2021\/04\/cabeceracontacto.jpg\u00bb text_orientation=\u00bbleft\u00bb custom_padding=\u00bb250px|100px|150px|100px|false|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb85%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700|||||||\u00bb text_text_color=\u00bb#2c2c2c\u00bb text_font_size=\u00bb40px\u00bb text_line_height=\u00bb1.1em\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>POL\u00cdTICA DE PRIVACIDAD\u00a0<i class=\"fa fa-chevron-right\" aria-hidden=\"true\" style=\"color: #e0083f;\"><\/i><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbfade\u00bb animation_delay=\u00bb250ms\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>DEHISPA, S.L le informa sobre su Pol\u00edtica de Privacidad respecto del tratamiento y protecci\u00f3n de los datos de car\u00e1cter personal de los usuarios y clientes que puedan ser recabados durante la navegaci\u00f3n, al comprar un producto o contratar un servicio a trav\u00e9s del sitio Web <a>https:\/\/www.dehispa.com<\/a>.<\/p>\n<p>En este sentido, DEHISPA, S.L garantiza el cumplimiento de la normativa vigente en materia de protecci\u00f3n de datos personales, reflejada en la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y de Garant\u00eda de Derechos Digitales (LOPD GDD). Cumple tambi\u00e9n con el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo de 27 de abril de 2016 relativo a la protecci\u00f3n de las personas f\u00edsicas (RGPD).<\/p>\n<p>El uso de sitio Web implica la aceptaci\u00f3n de esta Pol\u00edtica de Privacidad as\u00ed como las condiciones incluidas en el <a href=\"https:\/\/www.dehispa.com\/aviso-legal\/\">Aviso Legal<\/a>.<\/p>\n<h2>Identidad del responsable<\/h2>\n<ul>\n<li><b>Titular:<\/b><br \/>DEHISPA, S.L.\n<p>&nbsp;<\/p>\n<\/li>\n<li><b>NIF:<\/b> B80465172<\/li>\n<li><b>Domicilio:<\/b> Avenida de la Industria 3. 28760, Tres Cantos, Madrid, Madrid &#8211; Espa\u00f1a.<\/li>\n<li><b>Correo electr\u00f3nico:<\/b> info@dehispa.com<\/li>\n<li><b>Sitio Web:<\/b> <a>https:\/\/www.dehispa.com<\/a><\/li>\n<\/ul>\n<h2>Principios aplicados en el tratamiento de datos<\/h2>\n<p>En el tratamiento de sus datos personales, el Titular aplicar\u00e1 los siguientes principios que se ajustan a las exigencias del nuevo reglamento europeo de protecci\u00f3n de datos (RGPD):<\/p>\n<ul>\n<li><b>Principio de licitud, lealtad y transparencia:<\/b> El Titular siempre requerir\u00e1 el consentimiento para el tratamiento de los datos personales que puede ser para uno o varios fines espec\u00edficos sobre los que el Titular informar\u00e1 al Usuario previamente con absoluta transparencia.<\/li>\n<li><b>Principio de minimizaci\u00f3n de datos:<\/b> El Titular solicitar\u00e1 solo los datos estrictamente necesarios para el fin o los fines que los solicita.<\/li>\n<li><b>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n:<\/b> El Titular mantendr\u00e1 los datos personales recabados durante el tiempo estrictamente necesario para el fin o los fines del tratamiento. El Titular informar\u00e1 al Usuario del plazo de conservaci\u00f3n correspondiente <a href=\"#finalidad-del-tratamiento-de-datos-personales\">seg\u00fan la finalidad<\/a>.\n<p>En el caso de suscripciones, el Titular revisar\u00e1 peri\u00f3dicamente las listas y eliminar\u00e1 aquellos registros inactivos durante un tiempo considerable.<\/p>\n<\/li>\n<li><b>Principio de integridad y confidencialidad:<\/b> Los datos personales recabados ser\u00e1n tratados de tal manera que su seguridad, confidencialidad e integridad est\u00e9 garantizada.\n<p>El Titular toma las precauciones necesarias para evitar el acceso no autorizado o uso indebido de los datos de sus usuarios por parte de terceros.<\/p>\n<\/li>\n<\/ul>\n<h2>Obtenci\u00f3n de datos personales<\/h2>\n<p>Para navegar por <a>https:\/\/www.dehispa.com<\/a> no es necesario que facilite ning\u00fan dato personal.<\/p>\n<p>Los casos en los que usted s\u00ed proporciona sus datos personales son los siguientes:<\/p>\n<ul>\n<li>Al contactar a trav\u00e9s de los formularios de contacto o enviar un correo electr\u00f3nico.<\/li>\n<li>Al realizar un comentario en un art\u00edculo o en una p\u00e1gina.<\/li>\n<li>Al comprar un producto o contratar un servicio.<\/li>\n<\/ul>\n<h2>Derechos<\/h2>\n<p>El Titular le informa que sobre sus datos personales tiene derecho a:<\/p>\n<ul>\n<li>Solicitar el acceso a los datos almacenados.<\/li>\n<li>Solicitar una rectificaci\u00f3n o la cancelaci\u00f3n.<\/li>\n<li>Solicitar la limitaci\u00f3n de su tratamiento.<\/li>\n<li>Oponerse al tratamiento.<\/li>\n<\/ul>\n<p>No puede ejercitar el derecho a la portabilidad de los datos.<\/p>\n<p>El ejercicio de estos derechos es personal y por tanto debe ser ejercido directamente por el interesado, solicit\u00e1ndolo directamente al Titular, lo que significa que cualquier cliente, suscriptor o colaborador que haya facilitado sus datos en alg\u00fan momento, puede dirigirse a DEHISPA, S.L y pedir informaci\u00f3n sobre los datos que tiene almacenados y c\u00f3mo los ha obtenido, solicitar la rectificaci\u00f3n de los mismos, oponerse al tratamiento, limitar su uso o solicitar la cancelaci\u00f3n de esos datos en los ficheros del Titular.<\/p>\n<p>Para ejercitar sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n tiene que enviar<br \/>un correo electr\u00f3nico a info@dehispa.com junto con la prueba v\u00e1lida en derecho como una fotocopia del D.N.I. o equivalente.<\/p>\n<p>Tiene derecho a la tutela judicial efectiva y a presentar una reclamaci\u00f3n ante la autoridad de control, en este caso, la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, si considera que el tratamiento de datos personales que le conciernen infringe el Reglamento.<\/p>\n<h2 id=\"finalidad-del-tratamiento-de-datos-personales\">Finalidad del tratamiento de datos personales<\/h2>\n<p>Cuando usted se conecta al sitio Web para mandar un correo al Titular, escribe un comentario en un art\u00edculo o una p\u00e1gina, se suscribe a su bolet\u00edn o contrata un producto o un servicio est\u00e1 facilitando informaci\u00f3n de car\u00e1cter personal de la que el responsable es DEHISPA, S.L. Esta informaci\u00f3n puede incluir datos de car\u00e1cter personal como pueden ser su direcci\u00f3n IP, nombre y apellidos, direcci\u00f3n f\u00edsica, direcci\u00f3n de correo electr\u00f3nico, n\u00famero de tel\u00e9fono, y otra informaci\u00f3n. Al facilitar esta informaci\u00f3n, da su consentimiento para que su informaci\u00f3n sea recopilada, utilizada, gestionada y almacenada por<\/p>\n<p>\u2014<br \/>Listado de contactos v\u00eda formulario web almacenada en Arsys.es<\/p>\n<p>\u2014<br \/>s\u00f3lo como se describe en el <a href=\"https:\/\/www.dehispa.com\/aviso-legal\/\">Aviso Legal<\/a> y en la presente <a href=\"https:\/\/www.dehispa.com\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a>.<\/p>\n<p>Los datos personales y la finalidad del tratamiento por parte del Titular es diferente seg\u00fan el sistema de captura de informaci\u00f3n:<\/p>\n<ul>\n<li><b>Formularios de contacto:<\/b> El Titular solicita datos personales entre los que pueden estar: nombre y apellidos, direcci\u00f3n de correo electr\u00f3nico, n\u00famero de tel\u00e9fono y direcci\u00f3n de sitio Web con la finalidad de responder las consultas de los Usuarios, ofrecer informaci\u00f3n y demostraciones de los productos y servicios del Titular, incluidos presupuestos.\n<p>Por ejemplo, DEHISPA, S.L utiliza esos datos para dar respuesta a mensajes, dudas, quejas, comentarios o inquietudes que pueden tener los Usuarios relativas a la informaci\u00f3n incluida en el sitio Web, los productos y los servicios que se prestan a trav\u00e9s del sitio Web, el tratamiento de los datos personales, cuestiones referentes a los textos legales incluidos en el sitio Web, as\u00ed como cualquier otra consulta que el Usuario pueda tener y que no est\u00e9 sujeta a las condiciones del sitio Web o de las condiciones de contrataci\u00f3n.<\/p>\n<\/li>\n<li><b>Formularios de comentarios:<\/b> El Titular solicita datos personales entre los que pueden estar: nombre y apellidos, direcci\u00f3n de correo electr\u00f3nico, y direcci\u00f3n de sitio Web con la finalidad de responder a los comentarios de los Usuarios.<\/li>\n<li><b>Formularios de contrataci\u00f3n de productos o servicios:<\/b> El Titular solicita datos personales entre los que pueden estar: nombre y apellidos, documento de identidad (n\u00famero de identificaci\u00f3n fiscal, n\u00famero de identificaci\u00f3n de extranjero, pasaporte o permiso de residencia), direcci\u00f3n de correo electr\u00f3nico, direcci\u00f3n postal, n\u00famero de tel\u00e9fono y datos de pago (m\u00e9todos de pago o datos bancarios) con la finalidad de mantener una relaci\u00f3n comercial con el Usuario, realizar el env\u00edo de los pedidos, prestar los servicios contratados y para realizar la facturaci\u00f3n y el cobro de los productos o servicios contratados.<\/li>\n<\/ul>\n<p>Existen otras finalidades por las que el Titular trata datos personales:<\/p>\n<ul>\n<li>Para garantizar el cumplimiento de las condiciones recogidas en el <a href=\"https:\/\/www.dehispa.com\/aviso-legal\/\">Aviso Legal<\/a> y en la ley aplicable. Esto puede incluir el desarrollo de herramientas y algoritmos que ayuden a este sitio Web a garantizar la confidencialidad de los datos personales que recoge.<\/li>\n<li>Para apoyar y mejorar los servicios que ofrece este sitio Web.<\/li>\n<li>Para analizar la navegaci\u00f3n de los usuarios. El Titular recoge otros datos no identificativos que se obtienen mediante el uso de cookies que se descargan en el ordenador del Usuario cuando navega por el sitio Web cuyas caracter\u00edsticas y finalidad est\u00e1n detalladas en la <a href=\"https:\/\/www.dehispa.com\/politica-de-cookies\/\"> Pol\u00edtica de Cookies<\/a> .<\/li>\n<li>\n<p>Para gestionar las redes sociales. DEHISPA, S.L tiene presencia en redes sociales.<br \/>Si usted se hace seguidor en las redes sociales del Titular el tratamiento de los datos personales se regir\u00e1 por este apartado, as\u00ed como por aquellas condiciones de uso, pol\u00edticas de privacidad y normativas de acceso que pertenezcan a la red social que proceda en cada caso y que ha aceptado previamente.<\/p>\n<p>Puede consultar las pol\u00edticas de privacidad de las principales redes sociales en estos enlaces:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.facebook.com\/help\/cookies\" rel=\"nofollow noopener\" target=\"_blank\">Facebook<\/a><\/li>\n<li><a href=\"https:\/\/twitter.com\/privacy\" rel=\"nofollow noopener\" target=\"_blank\">Twitter<\/a><\/li>\n<li><a href=\"https:\/\/www.linkedin.com\/legal\/cookie-policy\" rel=\"nofollow noopener\" target=\"_blank\">Linkedin<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/privacy\" rel=\"nofollow noopener\" target=\"_blank\">YouTube<\/a><\/li>\n<li><a href=\"https:\/\/www.instagram.com\/legal\/privacy\/\" rel=\"nofollow noopener\" target=\"_blank\">Instagram<\/a><\/li>\n<\/ul>\n<p>El Titular tratar\u00e1 sus datos personales con la finalidad de administrar correctamente su presencia en la red social, informarle de sus actividades, productos o servicios, as\u00ed como para cualquier otra finalidad que las normativas de las redes sociales permitan.<\/p>\n<p>En ning\u00fan caso el Titular utilizar\u00e1 los perfiles de seguidores en redes sociales para enviar publicidad de manera individual.<\/p>\n<\/li>\n<\/ul>\n<h2>Seguridad de los datos personales<\/h2>\n<p>Para proteger sus datos personales, el Titular toma todas las precauciones razonables y sigue las mejores pr\u00e1cticas de la industria para evitar su p\u00e9rdida, mal uso, acceso indebido, divulgaci\u00f3n, alteraci\u00f3n o destrucci\u00f3n de los mismos.<\/p>\n<p>El sitio Web est\u00e1 alojado en Listado de contactos v\u00eda formulario web almacenada en Arsys.es. La seguridad de los datos est\u00e1 garantizada, ya que toman todas las medidas de seguridad necesarias para ello. Puede consultar su pol\u00edtica de privacidad para tener m\u00e1s informaci\u00f3n.<\/p>\n<h2>Contenido de otros sitios web<\/h2>\n<p>Las p\u00e1ginas de este sitio Web pueden incluir contenido incrustado (por ejemplo, v\u00eddeos, im\u00e1genes, art\u00edculos, etc.). El contenido incrustado de otras web se comporta exactamente de la misma manera que si hubiera visitado la otra web.<\/p>\n<p>Estos sitios Web pueden recopilar datos sobre usted, utilizar cookies, incrustar un c\u00f3digo de seguimiento adicional de terceros, y supervisar su interacci\u00f3n usando este c\u00f3digo.<\/p>\n<h2>Pol\u00edtica de Cookies<\/h2>\n<p>Para que este sitio Web funcione correctamente necesita utilizar cookies, que es una informaci\u00f3n que se almacena en su navegador web.<\/p>\n<p>En la p\u00e1gina <a href=\"https:\/\/www.dehispa.com\/politica-de-cookies\/\">Pol\u00edtica de Cookies<\/a> puede consultar toda la informaci\u00f3n relativa a la pol\u00edtica de recogida, la finalidad y el tratamiento de las cookies.<\/p>\n<p>&nbsp;<\/p>\n<h2>Legitimaci\u00f3n para el tratamiento de datos<\/h2>\n<p>La base legal para el tratamiento de sus datos es: el consentimiento.<\/p>\n<p>Para contactar con el Titular, suscribirse a un bolet\u00edn o realizar comentarios en este sitio Web tiene que aceptar la presente Pol\u00edtica de Privacidad.<\/p>\n<h2>Categor\u00edas de datos personales<\/h2>\n<p>Las categor\u00edas de datos personales que trata el Titular son:<\/p>\n<ul>\n<li>Datos identificativos.<\/li>\n<li>No se tratan categor\u00edas de datos especialmente protegidos.<\/li>\n<\/ul>\n<h2>Conservaci\u00f3n de datos personales<\/h2>\n<p>Los datos personales que proporcione al Titular se conservar\u00e1n hasta que solicite su supresi\u00f3n.<\/p>\n<div id=\"destinatarios\">\n<h2>Destinatarios de datos personales<\/h2>\n<ul>\n<li><b>Google Analytics<\/b> es un servicio de anal\u00edtica web prestado por Google, Inc., una compa\u00f1\u00eda de Delaware cuya oficina principal est\u00e1 en 1600 Amphitheatre Parkway, Mountain View (California), CA 94043, Estados Unidos (\u00abGoogle\u00bb).\n<p>Google Analytics utiliza \u00abcookies\u00bb, que son archivos de texto ubicados en tu ordenador, para ayudar al Titular a analizar el uso que hacen los Usuarios del sitio Web. La informaci\u00f3n que genera la cookie acerca del uso del sitio Web (incluyendo la direcci\u00f3n IP) ser\u00e1 directamente transmitida y archivada por Google en los servidores de Estados Unidos.<\/p>\n<p>M\u00e1s informaci\u00f3n en: <a href=\"https:\/\/policies.google.com\/privacy?hl=es-ES\" rel=\"nofollow noopener\" target=\"_blank\">https:\/\/analytics.google.com<\/a><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<p>En la p\u00e1gina de <a target=\"_blank\" href=\"https:\/\/policies.google.com\/privacy?hl=es\" rel=\"nofollow noopener\">Pol\u00edtica de privacidad de Google<\/a> se explica c\u00f3mo Google gestiona la privacidad en lo que respecta al uso de las cookies y otra informaci\u00f3n.<\/p>\n<p>Tambi\u00e9n puede ver una lista de los <a target=\"_blank\" href=\"https:\/\/policies.google.com\/technologies\/types?hl=es\" rel=\"nofollow noopener\">tipos de cookies<\/a> que utiliza Google y sus colaboradores y toda la informaci\u00f3n relativa al uso que hacen de las <a target=\"_blank\" rel=\"nofollow noopener\" href=\"https:\/\/policies.google.com\/technologies\/ads?hl=es\">cookies publicitarias<\/a>.<\/p>\n<h2>Navegaci\u00f3n Web<\/h2>\n<p>Al navegar por <a>https:\/\/www.dehispa.com<\/a> se pueden recoger datos no identificativos, que pueden incluir, la direcci\u00f3n IP, geolocalizaci\u00f3n, un registro de c\u00f3mo se utilizan los servicios y sitios, h\u00e1bitos de navegaci\u00f3n y otros datos que no pueden ser utilizados para identificarle.<\/p>\n<p>El sitio Web utiliza los siguientes servicios de an\u00e1lisis de terceros:<\/p>\n<ul>\n<li>Google Analytics.<\/li>\n<\/ul>\n<p>El Titular utiliza la informaci\u00f3n obtenida para obtener datos estad\u00edsticos, analizar tendencias, administrar el sitio, estudiar patrones de navegaci\u00f3n y para recopilar informaci\u00f3n demogr\u00e1fica.<\/p>\n<p>El Titular no se hace responsable del tratamiento de los datos personales que realicen las p\u00e1ginas web a las que pueda acceder a trav\u00e9s de los distintos enlaces que contiene el sitio Web.<\/p>\n<h2>Exactitud y veracidad de los datos personales<\/h2>\n<p>Usted se compromete a que los datos facilitados al Titular sean correctos, completos, exactos y vigentes, as\u00ed como a mantenerlos debidamente actualizados.<\/p>\n<p>Como Usuario del sitio Web usted es el \u00fanico responsable de la veracidad y correcci\u00f3n de los datos remitidos al sitio Web exonerando a DEHISPA, S.L de cualquier responsabilidad al respecto.<\/p>\n<h2>Aceptaci\u00f3n y consentimiento<\/h2>\n<p>Como Usuario del sitio Web declara haber sido informado de las condiciones sobre protecci\u00f3n de datos de car\u00e1cter personal, acepta y consiente el tratamiento de los mismos por parte de DEHISPA, S.L en la forma y para las finalidades indicadas en esta Pol\u00edtica de Privacidad.<\/p>\n<h2>Revocabilidad<\/h2>\n<p>Para ejercitar sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n tiene que enviar<br \/>un correo electr\u00f3nico a info@dehispa.com junto con la prueba v\u00e1lida en derecho como una fotocopia del D.N.I. o equivalente.<\/p>\n<p>El ejercicio de estos derechos no incluye ning\u00fan dato que DEHISPA, S.L est\u00e9 obligado a conservar con fines administrativos, legales o de seguridad.<\/p>\n<h2>Cambios en la Pol\u00edtica de Privacidad<\/h2>\n<p>El Titular se reserva el derecho a modificar la presente Pol\u00edtica de Privacidad para adaptarla a novedades legislativas o jurisprudenciales, as\u00ed como a pr\u00e1cticas de la industria.<\/p>\n<p>Estas pol\u00edticas estar\u00e1n vigentes hasta que sean modificadas por otras debidamente publicadas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE PRIVACIDAD\u00a0DEHISPA, S.L le informa sobre su Pol\u00edtica de Privacidad respecto del tratamiento y protecci\u00f3n de los datos de car\u00e1cter personal de los usuarios y clientes que puedan ser recabados durante la navegaci\u00f3n, al comprar un producto o contratar un servicio a trav\u00e9s del sitio Web https:\/\/www.dehispa.com. En este sentido, DEHISPA, S.L garantiza el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de privacidad - The Mining and Construction Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - The Mining and Construction Company\" \/>\n<meta property=\"og:description\" content=\"SERVICIOS DESCARGAS Descargue nuestro folletoOPERACI\u00d3N Y MANTENIMIENTOEn Dehispa completamos el ciclo de vida de tus proyectos, estando presente en la fase de post venta y realizando la operaci\u00f3n y el mantenimiento en sus tres vertientes; predictivo, preventivo y general. Mediante esta fase de operaci\u00f3n y mantenimiento, optimizamos la inversi\u00f3n realizada en cada proyecto, disminuyendo su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"The Mining and Construction Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dehispa.Oficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T13:28:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/\",\"url\":\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de privacidad - The Mining and Construction Company\",\"isPartOf\":{\"@id\":\"https:\/\/dehispa.com\/es\/#website\"},\"datePublished\":\"2021-04-30T09:26:09+00:00\",\"dateModified\":\"2025-05-12T13:28:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dehispa.com\/es\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dehispa.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dehispa.com\/es\/#website\",\"url\":\"https:\/\/dehispa.com\/es\/\",\"name\":\"Dehispa\",\"description\":\"Construcci\u00f3n, Miner\u00eda, Obra P\u00fablica e Industria\",\"publisher\":{\"@id\":\"https:\/\/dehispa.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dehispa.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dehispa.com\/es\/#organization\",\"name\":\"Dehispa\",\"url\":\"https:\/\/dehispa.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dehispa.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dehispa.com\/wp-content\/uploads\/2021\/06\/logotipo.png\",\"contentUrl\":\"https:\/\/dehispa.com\/wp-content\/uploads\/2021\/06\/logotipo.png\",\"width\":160,\"height\":53,\"caption\":\"Dehispa\"},\"image\":{\"@id\":\"https:\/\/dehispa.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Dehispa.Oficial\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - The Mining and Construction Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad - The Mining and Construction Company","og_description":"SERVICIOS DESCARGAS Descargue nuestro folletoOPERACI\u00d3N Y MANTENIMIENTOEn Dehispa completamos el ciclo de vida de tus proyectos, estando presente en la fase de post venta y realizando la operaci\u00f3n y el mantenimiento en sus tres vertientes; predictivo, preventivo y general. Mediante esta fase de operaci\u00f3n y mantenimiento, optimizamos la inversi\u00f3n realizada en cada proyecto, disminuyendo su [&hellip;]","og_url":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/","og_site_name":"The Mining and Construction Company","article_publisher":"https:\/\/www.facebook.com\/Dehispa.Oficial\/","article_modified_time":"2025-05-12T13:28:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/","url":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad - The Mining and Construction Company","isPartOf":{"@id":"https:\/\/dehispa.com\/es\/#website"},"datePublished":"2021-04-30T09:26:09+00:00","dateModified":"2025-05-12T13:28:08+00:00","breadcrumb":{"@id":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dehispa.com\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dehispa.com\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dehispa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/dehispa.com\/es\/#website","url":"https:\/\/dehispa.com\/es\/","name":"Dehispa","description":"Construcci\u00f3n, Miner\u00eda, Obra P\u00fablica e Industria","publisher":{"@id":"https:\/\/dehispa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dehispa.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dehispa.com\/es\/#organization","name":"Dehispa","url":"https:\/\/dehispa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dehispa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/dehispa.com\/wp-content\/uploads\/2021\/06\/logotipo.png","contentUrl":"https:\/\/dehispa.com\/wp-content\/uploads\/2021\/06\/logotipo.png","width":160,"height":53,"caption":"Dehispa"},"image":{"@id":"https:\/\/dehispa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dehispa.Oficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/pages\/1975"}],"collection":[{"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/comments?post=1975"}],"version-history":[{"count":9,"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/pages\/1975\/revisions"}],"predecessor-version":[{"id":239863,"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/pages\/1975\/revisions\/239863"}],"wp:attachment":[{"href":"https:\/\/dehispa.com\/es\/wp-json\/wp\/v2\/media?parent=1975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}